{"id":754,"date":"2026-01-25T14:15:35","date_gmt":"2026-01-25T14:15:35","guid":{"rendered":"https:\/\/decapederobeetdepee.fr\/?p=754"},"modified":"2026-01-25T14:15:37","modified_gmt":"2026-01-25T14:15:37","slug":"la-belle-et-le-corsaire-1957","status":"publish","type":"post","link":"https:\/\/decapederobeetdepee.fr\/index.php\/2026\/01\/25\/la-belle-et-le-corsaire-1957\/","title":{"rendered":"La Belle et le Corsaire (1957)"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Synopsis&nbsp;:<\/h2>\n\n\n\n<p>Un groupe de pirates barbaresques, men\u00e9s par Nadir El Krim, pillent et ravagent les c\u00f4tes m\u00e9diterran\u00e9ennes. De son c\u00f4t\u00e9, le baron Camerlata accueille la cousine de Charles Quint, Catherine d&rsquo;Autriche. Les pirates d\u00e9cident donc d&rsquo;assi\u00e9ger le ch\u00e2teau du baron pour enlever la dame et exiger une ran\u00e7on. Mais ils enl\u00e8vent par erreur Angela, la ni\u00e8ce de Camerlata.<\/p>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-ad2f72ca wp-block-group-is-layout-flex\">\n<h2 class=\"wp-block-heading\">R\u00e9alisation\u00a0: <\/h2>\n\n\n\n<p>G. M. Scotese<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sc\u00e9nario\u00a0: <\/h2>\n\n\n\n<p>Mario Amendola, Riccardo Pazzaglia, G. M. Scotese<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sortie\u00a0: <\/h2>\n\n\n\n<p>1957<\/p>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Casting\u00a0: <\/h2>\n\n\n\n<p>John Derek, Gianna Maria Canale, Ingeborg Sch\u00f6ner, Alberto Farnese, Raf Mattioli, Camillo Pilotto, Gianni Rizzo, Paul Muller, Yvette Masson, Mimmo Polli, Raf Baldassarre, Furio Meniconi, Carol Carter, Fausto Guerzoni, Ignazio Leone, Amina Pirani Maggi, Carlo Hintermann, Fanny Landini, Alberto Varelli, Silvio Lillo, Alberto Sorrentino<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"La Belle et le Corsaire ! Film Complet !\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/ilqCmS4wGbg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Plaisir de visionnage&nbsp;:<\/h2>\n\n\n\n<p>Un film \u00e0 la crois\u00e9e des genres (pirates, aventures, presque cape et d\u2019\u00e9p\u00e9e) int\u00e9ressant sur les id\u00e9es, mais avec une r\u00e9alisation un peu molle. Des personnages f\u00e9minins sympa, m\u00eame si tous manquent de profondeur.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"80\" src=\"https:\/\/decapederobeetdepee.fr\/wp-content\/uploads\/2025\/09\/Note-3-1.png\" alt=\"\" class=\"wp-image-341\"\/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Disponibilit\u00e9&nbsp;:<\/h2>\n\n\n\n<p>DVD<\/p>\n\n\n\n<p>Disponible sur YT<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Bonus Point Animaux Exotiques&nbsp;:<\/h2>\n\n\n\n<p>Rien. Snif.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/decapederobeetdepee.fr\/wp-content\/uploads\/2025\/08\/8-4.png\" alt=\"\" class=\"wp-image-162\"\/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Synopsis&nbsp;: Un groupe de pirates barbaresques, men\u00e9s par Nadir El Krim, pillent et ravagent les c\u00f4tes m\u00e9diterran\u00e9ennes. De son c\u00f4t\u00e9, le baron Camerlata accueille la cousine de Charles Quint, Catherine d&rsquo;Autriche. Les pirates d\u00e9cident donc d&rsquo;assi\u00e9ger le ch\u00e2teau du baron pour enlever la dame et exiger une ran\u00e7on. Mais ils enl\u00e8vent par erreur Angela, la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,17,20],"tags":[552,47,554,553,25,57,183,551],"class_list":["post-754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cinema","category-maritime","category-xvie","tag-552","tag-aventure","tag-canale","tag-charles-quint","tag-cinema","tag-cinema-italien","tag-pirate","tag-scotese"],"_links":{"self":[{"href":"https:\/\/decapederobeetdepee.fr\/index.php\/wp-json\/wp\/v2\/posts\/754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decapederobeetdepee.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decapederobeetdepee.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decapederobeetdepee.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/decapederobeetdepee.fr\/index.php\/wp-json\/wp\/v2\/comments?post=754"}],"version-history":[{"count":1,"href":"https:\/\/decapederobeetdepee.fr\/index.php\/wp-json\/wp\/v2\/posts\/754\/revisions"}],"predecessor-version":[{"id":756,"href":"https:\/\/decapederobeetdepee.fr\/index.php\/wp-json\/wp\/v2\/posts\/754\/revisions\/756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decapederobeetdepee.fr\/index.php\/wp-json\/wp\/v2\/media\/755"}],"wp:attachment":[{"href":"https:\/\/decapederobeetdepee.fr\/index.php\/wp-json\/wp\/v2\/media?parent=754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decapederobeetdepee.fr\/index.php\/wp-json\/wp\/v2\/categories?post=754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decapederobeetdepee.fr\/index.php\/wp-json\/wp\/v2\/tags?post=754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}